{"id":8069,"date":"2024-03-13T00:54:57","date_gmt":"2024-03-12T23:54:57","guid":{"rendered":"https:\/\/www.sf-germany.org\/einheiten\/uss-hephaistos\/for-every-time-there-is-a-season\/"},"modified":"2024-03-13T00:54:57","modified_gmt":"2024-03-12T23:54:57","slug":"for-every-time-there-is-a-season","status":"publish","type":"post","link":"https:\/\/www.sf-germany.org\/einheiten\/uss-hephaistos\/for-every-time-there-is-a-season\/","title":{"rendered":"For every time there is a season"},"content":{"rendered":"<div><meta http-equiv=\"Content-Type\"><br \/>\n<meta name=\"Generator\"><\/p>\n<div class=\"WordSection1\">\n<p class=\"MsoNormal\">Hallo Heph,<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">hier ein Copo von Oli und mir. Hat viel Spa\u00df gemacht! <\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">Gru\u00df<\/p>\n<p class=\"MsoNormal\">Debora<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">&lt;RPG&gt;<\/p>\n<p class=\"MsoNormal\"># Zeit: SpD\u00a0-1.2030<\/p>\n<p class=\"MsoNormal\"># Ort:\u00a0Quartier Jori Tainia<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">Der Eska sa\u00df in seinem Quartier nach einem anstrengenden Tag und versuchte trotz seiner M\u00fcdigkeit, irgendwie mit den beiden Tribble von Emily warm zu werden. Derzeit traute er sich noch nicht so richtig, sie einfach so in seinem Quartier herum&#8230;tribblen?.. zu lassen, aber immerhin hatten sie bereits die zweite Portion des extra im Replikator eingespeicherten Tribble-Futters verdr\u00fcckt und schienen guter Dinge. Eigentlich konnte nur Emily so etwas im Replikator eingespeichert haben.\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">Emily&#8230;wie es ihr wohl ging? Jori ging davon aus, er h\u00e4tte bereits etwas geh\u00f6rt, wenn sie&#8230; wenn sie&#8230; er wollte den Gedanken nicht zuende denken und beobachtete einfach nur die beiden Tribble von seiner Couch aus.\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">Unerwartet gab ihm seine T\u00fcr Bescheid, dass jemand zu ihm wollte. Neugierig rief er &#8222;Herein?&#8220;\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">Als die T\u00fcr sich \u00f6ffnete, kam Nazira herein. &#8222;Hallo Jori&#8230; hast Du einen Moment Zeit f\u00fcr mich?&#8220; Sie klang ebenfalls sehr m\u00fcde, aber auch&#8230; so, als h\u00e4tte sie geweint? Oder w\u00fcrde jeden Moment anfangen?\u00a0Und definitiv so, als w\u00fcrde sie gleich zusammenklappen. Auch ihre sonst so leichten Schritte waren schwer und langsam. Ihre Uniform sah so aus, als h\u00e4tte sie diese seit gestern nicht gewechselt.\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">Als der Eska Nazira so in seiner T\u00fcr stehen sah, sprang er\u00a0f\u00f6rmlich von der Couch auf. &#8222;Hallo Nazira, nat\u00fcrlich habe ich einen Moment f\u00fcr\u00a0Dich&#8230;f\u00fcr\u00a0Dich habe ich immer alle Zeit der Welt.&#8220; Mit wenigen Schritten hatte er die Strecke zwischen Couch und T\u00fcr \u00fcberwunden und stand nun direkt vor der kleinen Trill. Als er\u00a0sie so vor sich sah, war er sich nicht ganz sicher, ob er\u00a0sie k\u00fcssen,\u00a0oder lieber erstmal einfach fest in die Arme schlie\u00dfen sollte. Er entschied sich f\u00fcr letzteres. Er legte seine Arme um ihre Schultern und zog sie sanft an sich heran.\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">&#8222;Du siehst aus, als ob\u00a0Du gerade einiges durchgemacht hast&#8230;&#8220; murmelte er in ihr Ohr. Dann l\u00f6ste er die Umarmung, lie\u00df seine H\u00e4nde \u00fcber Naziras Oberarme nach unten gleiten und fasste schlie\u00dflich ihre H\u00e4nde. &#8222;Komm erst mal rein&#8230;kann ich\u00a0Dir vielleicht erstmal was anbieten?&#8220; fragte er mit ged\u00e4mpfter Stimme,\u00a0w\u00e4hrend er sie in sein Quartier vorsichtig hereinf\u00fchrte. Als sich die T\u00fcr hinter ihr schloss, wurde die kleine Trill durch das Gurren der beiden Tribbles ebenfalls begr\u00fc\u00dft.<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">Der Eska blickte kurz zu Ems Tribbles und dann wieder zu Nazira. &#8222;Ich habe noch zwei G\u00e4ste&#8230;&#8220; l\u00e4chelte Jori etwas schief. &#8222;&#8230;aber ich glaube, sie st\u00f6ren nicht weiter&#8230;&#8220;<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">&#8222;Lumina? Schneefl\u00f6ckchen? Ihr hier?&#8220; Nazira lie\u00df sich sofort auf die Knie fallen, um die Tribbles kurz zwischen ihre Hande zu nehmen. Beide gurrten begeistert, erinnerten sie sich doch noch an die Nacht, die sie bei ihr verbracht hatten, und Lumina leuchtete ein paar mal auf. &#8222;Hat Em sie &#8230; zu Dir gebracht, bevor sie auf die Nemesis ging..?&#8220; fragte die kleine Trill, zu Jori aufblickend.\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">&#8222;Nicht direkt &#8211; sie hatte sie zu Lt. Ajur gebracht, f\u00fcr den Fall, dass&#8230; aber er wollte sie nicht bei sich behalten und bat mich darum, ihn abzul\u00f6sen.&#8220; erkl\u00e4rte Jori kurz.\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">Pl\u00f6tzlich, die Tribble dicht an ihren Kopf haltend und auf ihr Gurren lauschend, begann die kleine silberhaarige Frau, zu schluchzen. &#8222;Sie hat&#8217;s geschafft&#8230; Euer Frauchen&#8230; kommt bald zu Euch zur\u00fcck&#8230;&#8220; erkl\u00e4rte sie den beiden kleinen Flauschb\u00e4llen durch ihre Schluchzer hindurch. Vorsichtig setzte sie sie wieder auf den Boden, blieb aber sitzen, wo sie war\u00a0und schlug sich die H\u00e4nde vors Gesicht. Jori konnte sehen, dass nun Tr\u00e4nen zwischen ihren Fingern hervorquollen, und ihre schmalen Schultern zuckten. &#8222;Tut mir Leid, Jori&#8230; ich&#8230; ich beruhige mich gleich wieder&#8230;&#8220;<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">Jori lie\u00df sich ebenfalls auf den Boden neben der Trill sinken. &#8222;Dir muss \u00fcberhaupt nichts leid tun, Nazira.&#8220; er legte sanft die H\u00e4nde auf Naziras Schultern. &#8222;Und\u00a0Du musst\u00a0Dich auch nicht gleich wieder beruhigen oderDich zusammenrei\u00dfen&#8230;&#8220; Er betrachtete die CNS f\u00fcr einige Momente und suchte ihren Blick und ihre gr\u00fcnen Augen. &#8222;Ich bin zwar kein Counselor&#8230;aber bei mir kannst\u00a0Du einfach\u00a0Du sein. Ich bin f\u00fcr\u00a0Dich da, nicht nur,\u00a0wenn es\u00a0Dir gut geht&#8230;&#8220; Er dr\u00fcckte ihre Schultern etwas und schwieg f\u00fcr einige Momente. Irgendwie kam es ihm merkw\u00fcrdig vor,\u00a0der CNS der Hephaistos solche Dinge zu sagen. Dinge, die sie mit Sicherheit selbst wusste und vermutlich auch schon zu zig\u00a0Crewmitgliedern w\u00e4hrend ihrer Arbeit gesagt hatte. Andererseits hatte auch eine CNS die gleichen Bed\u00fcrfnisse und Gef\u00fchle wie jeder andere auch. Und dennoch kam es dem Eska ein wenig schr\u00e4g vor, solche Dinge jetzt zu Nazira zu sagen, die vermutlich das Gesagte zu einem gewissen Grad auch mit dem beruflichen Ohr h\u00f6rte.\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">Der CSO atmete einmal tief durch.\u00a0&#8222;M\u00f6chtest\u00a0Du erz\u00e4hlen, was los ist?&#8220; fragte er schlie\u00dflich. &#8222;Nur.\u00a0wenn\u00a0Du m\u00f6chtest&#8230;&#8220;<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">&#8222;Halt mich einfach nur eine Weile fest, ja?&#8220; fl\u00fcsterte sie, und lie\u00df sich mit einem schweren Seufzer gegen seine breite Brust sinken, ihr Gesicht in seiner Uniform vergrabend. Bereitwillig schlo\u00df Jor die Arme um sie, und hielt sie fest. Einige Minuten lang, war nur das Gurren der Tribbles zu h\u00f6ren, die auf ihre Beine geklettert waren.\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">Als sich Nazira langsam wieder beruhigte, fing sie stockend an zu erz\u00e4hlen. &#8222;Wei\u00dft Du&#8230; das ist Teil meiner Sorgen gewesen&#8230; um ein Haar w\u00e4re ich eben\u00a0nicht\u00a0mehr ich selbst gewesen&#8230;zumindest nicht ganz&#8230;&#8220; murmelte sie. Als sie ihren\u00a0Kopf bewegte,\u00a0um sein \u00fcber sie gebeugtes, besorgtes Gesicht zu sehen, erkannte die Trill, dass er gar nichts verstand. Also holte sie tief Luft, und fing nochmal von vorne an.\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">&#8222;Ich war&#8230; die ganze letzte Nacht und bis gerade eben auf der Krankenstation der Nemesis. Emily und Karx&#8230; sie haben es geschafft&#8230; sie werden wieder ganz\u00a0gesund werden, sagen Dr. Zui und Jaxon.&#8220; Zitternd holte sie tief Luft, um sich weiter zu beruhigen, und Jori konnte nun deutlich sehen, wie \u00fcberm\u00fcdet sie war, aber da war noch mehr.\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">&#8222;Letzte Nacht&#8230; wurde ich auf die Nemesis gerufen&#8230; ich wusste erst gar nicht, warum. Dort&#8230; war noch eine weitere junge Trill aus der Mannschaft der Nemesis. Wir wurden untersucht&#8230; und uns wurde erkl\u00e4rt, dass wir notfalls&#8230; falls Em es nicht schaffen w\u00fcrde&#8230;dass eine von uns Karx \u00fcbernehmen m\u00fcsste&#8230;&#8220;\u00a0Ihre sonst so klangvolle Stimme war rau und sehr leise.<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">Der Eska versuchte,\u00a0das Gesagte zu Begreifen und einzuordnen. Er musste zugeben, dass er bisher recht wenig dar\u00fcber wusste, was es f\u00fcr einen Trill bedeutete,\u00a0mit einem Symbionten vereinigt zu werden. Bisher hatte er fast nur mit unvereinigten Trill zu tun gehabt. Und bei den wenigen Vereinigten, die er kannte, hatte er die Wirte vorher nie kennengelernt.\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">&#8222;Ich&#8230;ich glaube, ich verstehe&#8230;also zumindest einen Teil&#8230;&#8220; Jori hielt Nazira noch immer im Arm. &#8222;Kann denn jeder Trill einfach einen Symbionten \u00fcbernehmen, wenn es n\u00f6tig ist?&#8220; erkundigte sich Jori vorsichtig. Dabei behielt er die Aussage im Hinterkopf, dass sie fast nicht mehr sie selbst gewesen w\u00e4re&#8230;dabei konnte er nur im Ansatz erahnen, was sie damit meinte. Und er musste wieder mit Bedauern feststellen, dass er nicht wirklich viel \u00fcber die Spezies seiner Freundin wusste. Etwas, was er auf alle F\u00e4lle \u00e4ndern wollte&#8230;<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">Nazira verzog ein wenig das Gesicht bei seiner Frage. &#8222;Es ist\u00a0m\u00f6glich, aber alles andere als ideal. In der Regel wird auf Trill sehr genau ausgew\u00e4hlt, wer die Ehre erh\u00e4lt, sich vereinigen zu d\u00fcrfen. So etwas wie letzte Nacht&#8230; das wird nur in Betracht gezogen, wenn es keine andere M\u00f6glichkeit gibt, den Symbionten am Leben zu erhalten.. Du musst wissen, es gibt sehr viel weniger Symbionten, als Trill. Und da sie sozusagen ewig leben k\u00f6nnen, sind sie uns unendlich kostbar. Jeder traditionell aufgewachsene Trill w\u00fcrde niemals z\u00f6gern, wenn n\u00f6tig, das \u00dcberleben eines Symbionten \u00fcber sein eigenes zu stellen&#8230; nun, die Trill von der Nemesis geh\u00f6rte offenbar nicht dazu. Sie&#8230; hat sich geweigert und ist von der Krankenstation gefl\u00fcchtet. Also blieb nur ich&#8230; und f\u00fcr einen Moment sah es so aus, als w\u00fcrde Emily.. es nicht schaffen&#8230;&#8220; ein erneuter Schluchzer unterbrach die Erz\u00e4hlung der kleinen silberhaarigen Frau. &#8222;Ich&#8230; ich wusste, falls Emily sterben w\u00fcrde, w\u00e4re es meine Pflicht&#8230; die ich nat\u00fcrlich sofort erf\u00fcllt h\u00e4tte&#8230; aber trotzdem&#8230; Jori, ich hatte solche Angst. Angst um Emily, ich mag sie sehr, und nat\u00fcrlich will ich sie nicht verlieren, aber auch&#8230; auch Angst um uns&#8230;&#8220; ihre gro\u00dfen gr\u00fcnen Augen sahen hoch in seine, und er sah die eben beschriebene Angst, aber auch Scham in ihnen. Scham, dass sie am liebsten ebenfalls gefl\u00fcchtet w\u00e4re.\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">&#8222;Wei\u00dft Du&#8230; wenn ein Trill mit einem Symbionten vereinigt wird, vermischen sich beide. Jeder Wirt bringt seinen eigenen Charakter, seine eigenen Erfahrungen mit ihn die Verbindung, der Symbiont aber auch&#8230; und dazu noch alle Erinnerungen seiner Vorwirte. Die beiden&#8230;vermischen sich, zu einem neuen Wesen, das Charakterz\u00fcge und Erinnerungen von Wirt\u00a0und\u00a0\u00a0Symbiont hat. H\u00e4tte ich Karx \u00fcbernehmen m\u00fcssen, dann&#8230;. w\u00e4re ich jetzt Nazira Karx, und auch, wenn ich noch ich w\u00e4re, w\u00e4re ich doch viel mehr&#8230; und anders. Au\u00dferdem&#8230; Karx ist sehr alt, und sehr&#8230;speziell. Ich&#8230;glaube nicht, dass wir miteinander harmoniert h\u00e4tten&#8230;&#8220;<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">Die ganze Zeit h\u00f6rte der Eska sehr aufmerksam zu. Aber auch seinen Blicken entgingen die verschienden Emotionen der jungen Trill, die sich auf ihrem Gesicht und in ihren Augen abzeichneten in keinster Weise. Er konnte auch nach Naziras Ausf\u00fchrungen bei Weitem nicht behaupten, dass er alle Implikationen einer Vereinigung verstanden hatte. Aber konnte verstehen, dass eine Vereinigung eine gewaltige Ver\u00e4nderung f\u00fcr den Wirt bedeutete. Dass dies f\u00fcr einige Trill die Erf\u00fcllung all\u00a0ihrer\u00a0Tr\u00e4ume war,\u00a0oder schlicht die Erf\u00fcllung einer Pflicht &#8211; oder eben auch ein Alptraum. Diese Aspekte wiederum konnte er nur allzu\u00a0gut\u00a0verstehen. F\u00fcr ihn war es ein Traum,\u00a0ein tradtioneller Eska-J\u00e4ger zu sein, f\u00fcr die meisten anderen Eska w\u00e4re das eher das Gegenteil. Auch hatte er w\u00e4hrend seines DIenstes bei der Eska-Marine junge Besatzungsmitglieder gesehen, die viel lieber geflohen w\u00e4ren, als sich den Cardassianern entgegenzustellen und sich gleichzeitig daf\u00fcr gesch\u00e4mt hatten, obwohl sie nicht flohen. Aber alleine der Gedanke an Flucht war schon zu viel\u00a0f\u00fcr\u00a0sie, wenn sie sahen, wie selbstverst\u00e4ndlich sich ihre Kameraden der SItuation stellten.<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">&#8222;Ich&#8230;ich&#8230;kann nicht behaupten, dass ich alles v\u00f6llig verstanden habe, was\u00a0Du mir gerade \u00fcber die Vereinigung erz\u00e4hlt hast&#8230;&#8220; begann Jori mit ruhiger sanfter Stimme. &#8222;Aber ich kann glaube ich ganz gut nachf\u00fchlen, was in\u00a0Dir vorgegangen ist&#8230;wie\u00a0Du zwischen Pflicht und deinen Bed\u00fcrfnissen hin- und hergerissen\u00a0gewesen\u00a0sein musstest&#8230;.Deine \u00c4ngste und Sorgen&#8230;&#8220; seine Stimme verlor sich als er dar\u00fcber nachdachte, was alles h\u00e4tte passieren k\u00f6nnen&#8230;und was am Ende wirklich passiert war,\u00a0und dass\u00a0die Geschichte wohl f\u00fcr alle gut ausgegangen zu sein schien. Er strich Nazira z\u00e4rtlich durch ihre Haare.<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">Diese l\u00e4chelte ihn durch ihre Tr\u00e4nen an, unendlich dankbar f\u00fcr seine aufmerksame, f\u00fcrsorgliche Ader, die er gerade zeigte &#8211; und begann auch schon gleich wieder, sich selbst zu analysieren. &#8222;Danke, Jori&#8230; danke, dass Du f\u00fcr mich da bist. Ich weine jetzt auch nur aus&#8230; Erleichterung, dass es Emily wieder gut gehen wird, dass sie bei uns bleibt, und.. ich nicht in die Bresche springen musste&#8230; und ich habs den ganzen Tag und die ganze Nacht versucht drinnen zu halten, und stark zu wirken, ich konnte dem Captain nicht noch mehr Sorgen machen, und Emily hat mich gebraucht, auch, wenn sie meistens bewusstlos war, und&#8230; ach, es brach sich jetzt einfach Bahn, als ich Schneefl\u00f6ckchen und Lumina gesehen habe&#8230; weil ich wei\u00df, Emily hat auf ihre Art versucht, Vorsorge f\u00fcr den schlimmsten Fall zu treffen&#8230; es tut mir Leid, dass Du das jetzt alles abkriegst.&#8220;\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">Noch leicht schn\u00fcffelnd, aber nicht mehr weinend, vergrub die kleine Frau nochmal ihr Gesicht in seiner Uniform und seufzte tief, seinen ganz eigenen Duft in sich aufsaugend. &#8222;Au\u00dferdem habe ich seit 36 Stunden nicht geschlafen&#8230;. da hab ich mich einfach nicht mehr gut im Griff&#8230;&#8220; murmelte sie in seine Brust.\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">Jori zog Nazira etwas fester an sich an. &#8222;DIr muss das hier nicht Leid tun. Wie gesagt, ich bin f\u00fcr\u00a0Dich\u00a0da&#8230;&#8220; murmelte er ihr in ihr Ohr. In Gedanken f\u00fcgte er unwillk\u00fcrlich hinzu: Wie in guten als auch in schlechten Zeiten&#8230; bei diesem Gedank erschrak\u00a0der Eska fast ein wenig, doch schon im n\u00e4chsten Moment legte sich ein kleines L\u00e4cheln auf seine Lippen.<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">&#8222;Du hast also Erfahrung mit Emilys Tribbles?&#8220; fragte er schlie\u00dflich, als die beiden \u00fcber ihre\u00a0Beine\u00a0liefen.<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">&#8222;Ja&#8230;ja, ich habe mich auch schonmal um die\u00a0beiden\u00a0gek\u00fcmmert&#8230;&#8220; fl\u00fcsterte die kleine Trill leise.<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">&#8222;Dann kannst du mir\u00a0vielleicht einen Tipp mit ihrem Futter geben&#8230;ich habe zwar mit vielen Tierarten Erfahrungen&#8230;&#8220;,\u00a0dabei dachte er an seine Ausbildung als Eska-J\u00e4ger und seine Zeit als WIldh\u00fcter in der Grafschaft Grant, &#8222;aber mit Tribbles\u00a0habe ich bisher keine Erfahrungen gemacht.&#8220;<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">&#8222;Hm&#8230;ja&#8230;sie&#8230;sie fressen gerne&#8230;Emilys Futter&#8230;aus dem Replikator&#8230;.&#8220;,\u00a0murmelte Nazira schl\u00e4frig&#8230;, &#8222;aber wenn Du sie zum Schlafen kriegen willst, klappt es gut, ihne was vorzusingen&#8230;&#8220;<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">Sie sah auf die beiden Tribbles herunter, die erwartungsvoll auf ihrem Scho\u00df hockten. &#8222;Ihr zwei seid bestimmt auch m\u00fcde..?&#8220; Nazira l\u00f6ste sich langsam von Jori, fast z\u00f6gerlich, als wollte sie seine warme Umarmung nicht verlassen, nahm dei beiden Tribble-Damen vorsichtig hoch und setzte sie auf ein Kissen auf der Couch. Dann sa\u00df sie schr\u00e4g auf dem Boden vor der Couch, lehnte ihren Arm auf die Sofakante und legte ihren Kopf schief darauf. Ein paar Sekunden sp\u00e4ter konnte Jori vernehmen, wie sie begann, den beiden ein Lied vorzusingen. Ihre Stimme war noch immer etwas rau vom Weinen und der Ersch\u00f6pfung, und er kannte das Lied nicht, aber es klang deutlich nach einem Schlaflied ihrer Heimatwelt, in der Sprache der Trill.\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">Die beiden Tribbles gurrten leise im Takt mit, und bald schon dimmte sich Lumias helles Leuchten ab und die beiden Flauschb\u00e4lle wurden ruhiger und h\u00f6rten schlie\u00dflich auf, sich zu bewegen und zu gurren. Ein L\u00e4cheln schlich sich auf Naziras Z\u00fcge, als sie noch ein wenig weitersang, nun mit geschlossenen Augen, und ihre Stimme wurde immer langsamer und leiser. Schlie\u00dflich brach sie mitten in einer Zeile komplett ab&#8230; und als sich Jori etwas vobeugte um ihr Gesicht zu sehen, war sie ebenfalls eingeschlafen.\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">Erstaunt blickte der Eska die Trill an. Hatte sie sich quasi selbst in den Schlaf gesungen? Geht sowas \u00fcberhaupt? fragte sich Jori, als er die nun sanften und weichen Z\u00fcge von Nazira betrachtete. F\u00fcr ein paar Augenblicke geno\u00df er diesen Anblick. Dann stand er langsam auf, schob seine Arme unter Naziras Beine und R\u00fccken und hob sie ganz vorsichtig auf. Er \u00fcberlegte f\u00fcr einen winzigen Augenblick, ob er sie auf die Couch legen sollte, doch dann entschied er sich daf\u00fcr, sie in sein Bett zu legen, das zweifelsohne bequemer war.\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">Als er sie bewegte und aufhob, murmelte sie schlaftrunken etwas, kuschelte sich aber sofort an seine Brust und schlief weiter.<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">Die wenigen Schritte zum Bett hatte er schnell mit Nazira in den Armen \u00fcberwunden. Sanft legte er sie aufs Bett. Anschlie\u00dfend zog er ihr behutsam zun\u00e4chst die Stiefel aus, \u00f6ffnete ihre Uniformjacke, streifte diese von ihrem Oberk\u00f6rper ab und wiederholte dies bei ihrer Uniformhose. Dann deckte er sie zu, zog sich selbst die Uniform aus und schl\u00fcpfte neben der Trill unter die Decke. Dabei kuschelte er sich dicht\u00a0an sie ran, legte einen Arm um sie und geno\u00df schlicht ihre N\u00e4he und W\u00e4rme, bevor auch er mit einem breiten L\u00e4cheln neben ihr einschlief.<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">#\u00a0Zeit: SpD 3.2200<\/p>\n<p class=\"MsoNormal\">#\u00a0Ort: Station K7 &#8211; Tanbar &#8222;Wunderbar&#8220;\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">&lt;Zitat&gt;<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">Sureya war mit ihrem Tanzpartner ebenfalls an den Tisch gekommen. Dort applaudierten ihr nochmal alle.<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">\u201eNun Miss Bateh, ich w\u00fcrde sagen, dass das eine ganz w\u00f6rtlich umwerfende Performance war.\u201c Sagte Ettore, dessen geschultes Auge die vielen Stunden Arbeit sofort erkannt hatten.<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">\u201eWie oft trainieren Sie?\u201c erkundigte er sich.<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">&lt;\/Zitat&gt;<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">&#8222;So oft es m\u00f6glich ist, Mr. della Scala. Mindestens drei mal pro Woche. Sie erinnern sich doch gewiss noch an unsere T\u00e4nze auf der Hephaistos damals?&#8220; Sie zeigte wie immer ihr k\u00e4tzisches Grinsen. &#8222;Aber nat\u00fcrlich f\u00e4llt es leichter, regelm\u00e4\u00dfig zu \u00fcben, wenn man einen guten Tanzpartner hat.&#8220; Ihr Grinsen schwenkte kurz hoch zu ihrem EO, Ratan Vaish, der sehr nah hinter ihrer Schulter stand und ihr L\u00e4cheln ruhig wie ein Heiliger erwiderte. &#8222;Und Sie wissen ja, was man sagt: Tanzen ist wie Fahrradfahren. Das verlernt man nicht.&#8220;<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">Fast wie unbewusst hatte sie dabei \u00fcber den Unterarm ihres Tanzpartners gestrichen, der locker um ihre Taille gelegt war, als w\u00fcrden sie gleich wieder lostanzen wollen,\u00a0doch wer Sureya kannte, wusste, dass ihr solche unbewussten Dinge nie passierten.<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">(NRPG: Kleiner R\u00fcckball zu Kim, falls Du die Unterhaltung noch fortf\u00fchren m\u00f6chtest.)<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">Jori und Nazira hatten sich, nachdem sich die Aufregung um Melody gelegt hatte, ein breites Grinsen geteilt. Nazira stellte sich kurz auf die Zehenspitzen, um dem viel gr\u00f6\u00dferen Eska ins Ohr zu raunen &#8222;Ich bin zwar lange nicht so gut wie sie, aber was meinst Du,\u00a0wollen wir&#8217;s mal versuchen?&#8220;, wobei sie auf die Tanzfl\u00e4che deutete.\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">Der Eska blickte etwas verdutzt zu der kleinen Trill herunter. Klar waren sie alle hier mehr oder weniger gelandet, um etwas Spa\u00df zu haben und auch um am Ende zu tanzen. Nach der Vorstellung der CO und des XOs der Nemesis gerade eben w\u00fcrde,\u00a0egal wer dort als n\u00e4chstes rausginge,\u00a0ziemlich alt aussehen. Und was noch dazu kam war, dass Jori zwar ein wenig\u00a0zappeln\u00a0konnte, Paartanz hatte er aber nur ein paar Mal w\u00e4hrend der Akademie mit Tessa probiert. Und eigentlich auch nur, weil sie ihn damals ein paar Mal zu diesem Akademie-Sportkurs mit hingeschleift hatte.<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">&#8222;\u00c4h&#8230;was meinst du genau?&#8220; fragte Jori ein wenig verunsichert nach. &#8222;Also tanzen ist schon klar, aber meinst du die Art, was Captain Bateh getanzt haben oder \u00e4h&#8230;.Freistil?&#8220;\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">Nazira kicherte etwas. &#8222;Naja, das was Captain Bateh Und Commander Vaish eben geliefert hat, k\u00f6nnen wir sicher nicht nachmachen. Aber so einen kleinen Foxtrott oder Chacha kriegen wir doch bestimmt hin, oder? Komm, lass es uns versuchen!&#8220; Sie zog ein wenig an seiner Hand, offenbar gerade ein wenig ausgelassener, als sonst.\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">Foxtrott? Chacha? Das waren alles irdische T\u00e4nze, glaubte Jori zumindest. Aber\u00a0wie\u00a0diese noch\u00a0gleich\u00a0gingen&#8230;An der Akademie gab es in besagtem\u00a0Kurs zwei recht gute Tanzlehrer. Die wussten, wie man f\u00fchrte,\u00a0und mit ihnen war dass alles immer ganz leicht. Wenn es dann aber an die gleiche Schrittfolge zusammen mit Tessa ging&#8230;ein kalter Schauer lief dem Eska den R\u00fccken runter. Aber aus der Nummer kam er wohl jetzt nicht mehr raus.<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">Auf der Tanzfl\u00e4che angekommen, l\u00e4chelte Nazira Jori breit an: &#8222;Darf ich bitten?&#8220; und streckte dabei ihre rechte Hand in die H\u00f6he. Unsicher blickte er Eska auf ihre Hand und versuchte,\u00a0sich an die Tanzhaltung f\u00fcr diese Art von T\u00e4nze zu erinnern. Er atmete einmal tief durch und sp\u00fcrte bereits die ersten Blicke von Jestun und Massimo in seinem R\u00fccken. Dann ergriff er mit seiner linken Hand die ihm entgegen gestreckte Hand, trat etwas n\u00e4her an die kleine Trill heran und legte seine rechte Hand auf ihr linkes Schulterblatt.\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">Jori schaute noch einmal Narzira mit einem fast \u00e4ngstlichen Blick an: &#8222;Bist du sicher, dass das\u00a0jetzt\u00a0eine gute Idee ist?&#8220; versuchte er es noch einmal schwach&#8230; In diesem\u00a0Augenblick erklangen die ersten T\u00f6ne des n\u00e4chsten Lieds und die ersten Zeilen des Textes kamen aus den Boxen.\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">&lt;NRPG&gt;\u00a0<a href=\"https:\/\/www.youtube.com\/watch?v=6JCLY0Rlx6Q\" rel=\"nofollow noopener\" target=\"_blank\"><span style=\"text-decoration:none;\">https:\/\/www.youtube.com\/watch?v=6JCLY0Rlx6Q<\/span><\/a>\u00a0&lt;\/NRPG&gt;<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">She took my arm\u00a0<\/p>\n<p class=\"MsoNormal\">I don&#8217;t know how it happened\u00a0<\/p>\n<p class=\"MsoNormal\">We took the floor and she said&#8230;<\/p>\n<p class=\"MsoNormal\">Shut up and Dance with me!<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">Die kleine Trill kicherte. &#8222;Wie passend.&#8220; Unauff\u00e4llig bewegte sie ihre Schultern etwas, so dass seine Hand auf ihrem R\u00fccken in die richtige Position rutschte. &#8222;Und wenn nicht jetzt, wann dann?&#8220; Sie blinzelte schelmisch zu ihm hoch und erg\u00e4nzte &#8222;Versuch, nicht auf Deine F\u00fc\u00dfe, sondern in meine Augen zu gucken. Und wir kriegen das schon hin.&#8220;\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">Jori hatte keine Probleme damit, in Naziras Augen zu sehen, ganz im Gegenteil &#8211; aber ihr nicht auf die F\u00fc\u00dfe zu treten, das war nicht so einfach. Sie bewegten sich ein paar Schritte, doch noch bevor sie richtig in den Rhythmus fallen konnten, stand er schon auf ihren kleinen Zehen. &#8222;Autsch!&#8220; Doch sie kicherte. &#8222;Komm, versuch&#8217;s nochmal..&#8220;<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">&#8222;Ah&#8230;das ist alles immer viel schwieriger, als es aussiehst&#8230;.&#8220;kommentierte Jori etwas verlegen seine Versuche,\u00a0sich zum Rhythmus zu bewegen, die\u00a0F\u00fc\u00dfe dabei richtig zu sortieren und dabei nicht die F\u00fc\u00dfe von Nazira zu treffen. Doch so recht wollte ihm das nicht gelingen, als er ein paar Schritte sp\u00e4ter schon wieder auf einem der F\u00fc\u00dfe der Trill landete.<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">&#8222;Tut mir echt leid&#8230;&#8220; murmelte Jori mit wachsender Verlegenheit. Denn es war nicht nur genug, dass er gerade auf Naziras F\u00fc\u00dfen rumzutrampeln schien, sondern dass sie immer mehr Augenpaare auf sich zu ziehen schienen. Dabei scho\u00df ihm unwillk\u00fcrlich ein Spruch der Tanzlehrer von damals ins\u00a0Ged\u00e4chtnis: Wer drunter steht hat meist falsch getanzt&#8230;.Wie wenig hilfreich dieser Satz doch war&#8230;<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">Die Gruppe der anderen Sternenflottenoffiziere, die sich bis jetzt angeregt unterhalten hatte, war nun auch auf das ungl\u00fcckliche Tanzp\u00e4rchen aufmerksam geworden. Gerade Sureya konnte kaum noch ihrer Unterhaltung mit Ettore folgen. Beim n\u00e4chsten Trampler auf Naziras F\u00fc\u00dfe und der damit einhergehenden Unterbrechnung des Tanzes, zuckte sie leicht zusammen und sog scharf die Luft zwischen den Z\u00e4hnen ein. &#8222;Bei Hathor, das ist ja nicht mit anzusehen&#8230;. Mr. della Scala, bitte entschuldigen Sie mich f\u00fcr einen Moment.&#8220; Und zu ihrem EO: &#8222;Ratan, kommen Sie mit. Wir haben eine Aufgabe.&#8220; Kurzentschlossen, zog sie den gro\u00dfen Mann an seiner Hand hinter sich her. Dieser wehrte sich nicht, sondern folgte ihr einfach grinsend &#8211; er kannte seine Chefin bereits zu gut.<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">Als die beiden bei Jori und Nazira ankamen, verlor Sureya keine Sekunde. &#8222;Mir ist aufgefallen, dass Sie beide etwas Unterst\u00fctzung brauchen k\u00f6nnten.&#8220; Sie grinste breit. &#8222;D\u00fcrfen wir? Ich unterrichte zuf\u00e4llig auch und kann Ihnen bestimmt behilflich sein.&#8220;\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">Nazira sah mit leicht offen stehendem Mund zu den beiden.\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">Auch Jori blickte zu beiden Offizieren mit einer Mischung aus \u00dcberraschung und blanken Entsetzen. &#8222;Captain Bateh, Commander Vaish&#8230;&#8220; Dem Eska war es mehr als unangehm, dass sie nicht nur die Aufmerksamkeit der Hephaistoscrew inklusive seines COs nun voll und ganz hatten,\u00a0sonder obendrein auch noch die der Kommandooffiziere eines anderen Schiffs. Jori blickte etwas verloren zu Nazira hin\u00fcber. Allerdings schien sich diese nicht viel anders zu f\u00fchlen.<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">&#8222;&#8230;vielen Dank f\u00fcr\u00a0Ihr Angebot&#8230;aber&#8230;aber machen\u00a0Sie sich bitte keine Umst\u00e4nde&#8230;.&#8220; begann Jori.<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">Sureya winkte zackig ab. &#8222;Papperlapapp. Das sind keine Umst\u00e4nde. Es ist eine Mission.&#8220; Sie grinste wieder, diesmal weniger w\u00f6lfisch, eher einnehmend. &#8222;Aber bitte lassen Sie doch die R\u00e4nge vor der T\u00fcr, Mr&#8230;.Tainia, richtig?&#8220; Der angesprochene nickte.\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">&#8222;Ich w\u00fcrde einen kurzen Partnerwechsel vorschlagen, damit wir Ihnen beiden einzeln rasch die wenigen n\u00f6tigen Schritte zeigen k\u00f6nnen, und dann&#8230;eine gemeinsame \u00dcbung. Einverstanden?&#8220; Das Grinsen wurde wieder breiter.\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">&#8222;Ahem&#8230;vielen Dank, Miss Bateh. Sehr gerne.&#8220; Nazira konnte und wollte jetzt einfach nur noch h\u00f6flich sein, und schenkte Jori ein schiefes L\u00e4cheln und ein leichtes Achselzucken.\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">Kurz darauf hatte Jori Sureya im Arm, und Ratan Vaish hatte seinen Arm um Nazira gelegt. Das n\u00e4chste Lied begann, ein einfacher vierer-Takt, und die beiden erfahrenen T\u00e4nzer erkl\u00e4rten leise und ruhig, wie die Schrittabfolge war, und legten dann los. &#8222;Sehen Sie mir in die Augen, Miss Tapai&#8220;, sagte die dunkle, weiche Stimme des gro\u00dfen attraktiven Inders, und Nazira sah hoch in seine schwarzen Augen. &#8222;Und sp\u00fcren Sie, wohin ich sie lenke. Sie m\u00fcssen nur die simplen Schritte im Kopf behalten, und mich den Rest machen lassen. Ich zeige Ihnen, wo sie hinm\u00fcssen, keine Sorge.&#8220; Er l\u00e4chelte sie an, seine wei\u00dfen Z\u00e4hne blitzten im Halbdunkel des Tanzlokals auf.\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">Gleichzeitig erkl\u00e4rte Sureya Jori etwas ganz \u00e4hnliches. &#8222;Vor, vor, seit, zur\u00fcck. Ja, genau. Sehen Sie mir in die Augen, Mr. Tainia. Wer auf seine F\u00fc\u00dfe schaut, ist schon halb gestolpert. Eigentlich m\u00fcssten\u00a0Sie mich\u00a0f\u00fchren, aber damit Sie ein Gef\u00fchl daf\u00fcr bekommen, erlauben Sie mir kurz, dass\u00a0ich Sie\u00a0f\u00fchre, auch, wenn&#8217;s komisch wirkt. Ihre Hand auf meinem Schulterblatt bitte etwas fester. Sie sollten damit in der Lage sein, ihre Partnerin zu f\u00fchren, nicht, sich an ihrem Oberteil festzuhalten. Ich zeig es ihnen, so.&#8220; und schon sp\u00fcrte er ihren festen Griff auf seinem Schulterblatt, der ihm erstaunlich pr\u00e4zise anzeigte, wohin er sich als n\u00e4chstes bewegen sollte. Die Augen der kleinen \u00c4gypterin waren beinahe genauso gr\u00fcn, wie die von Nazira&#8230; und doch so anders. W\u00e4hrend sie sich langsam \u00fcber den Tanzboden bewegten, konnte er die kleinen Perlen an den Enden ihrer Z\u00f6pfe aneinander klicken h\u00f6ren.\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">Jori versuchte sich auf das zu konzentrieren, was ihm Sureya gesagt,\u00a0aber auch gleichzeitig gezeigt hatte. Und dies am Ende auch umzusetzen. Mit ihr zusammen gelang ihm das seiner Meinung nach auch ganz gut. Allerdings wusste er jetzt schon\u00a0dass,\u00a0sobald Nazira und er es wieder zusammen probieren sollten, es wieder in blauen\u00a0Flecken f\u00fcr Nazira enden w\u00fcrde. Scheinbar hatten alle Tanzlehrer die Begabung,\u00a0ihre Sch\u00fcler so zu f\u00fchren, dass alles ganz leicht wirkte, solange\u00a0man\u00a0mit mit ihnen tanzte. Diese Leichtkeit war dann aber sofort wie weggeblassen, sobald man es mit seinem Tanzpartner umsetzen sollte.<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">&#8222;Sie m\u00fcssen schon in Gedanken auf dem Parkett und\u00a0bei\u00a0ihrer Partnerin\u00a0sein, Mr Tainia&#8220;,\u00a0holte die \u00c4gypterin den Eska wieder zu sich zur\u00fcck. &#8222;Das ist eigentlich auch schon fast das ganze Geheimnis.&#8220; grinste diese weiter.<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">&#8222;Und die ganzen anderen kleinen Feinheiten wie Schrittfolgen, Rhythmusgef\u00fchl, K\u00f6rperspannung und F\u00fchrung&#8230;.&#8220; wagte sich Jori ein wenig verbal aus der Deckung.\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">Sie grinste ihn von unten her an, und er konnte sich vorstellen, was f\u00fcr eine Wirkung sie fr\u00fcher, als sie noch sehr viel j\u00fcnger war, auf die halbe Mannschaft ihres damaligen Schiffes gehabt haben musste. &#8222;Das h\u00e4ngt alles zusammen.&#8220;\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">Das Lied endete, und Sureya machte eine kleine, bestimmende Geste zum DJ, die dieser mit einem Nicken beantwortete.\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">&#8222;So, und jetzt probieren Sie es bitte wieder gemeinsam. Und zur Unterst\u00fctzung&#8230; werden wir mit Ihnen zusammen tanzen.&#8220; Konnte diese drahtige kleine Frau etwas anderes, als breit zu grinsen? Gewiss&#8230; nur jetzt hier gerade nicht.\u00a0<\/p>\n<p class=\"MsoNormal\"><span style=\"\">\u00a0<\/span><\/p>\n<p class=\"MsoNormal\">&#8222;Sie meinen &#8211; neben uns?&#8220; fragte Nazira neugierig. Offenbar hatte sie auch ein gutes Erlebnis mit Ratan Vaish gehabt.\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">&#8222;Nein, hinter ihnen.&#8220; raunte dieser ihr l\u00e4chelnd ins Ohr, und wechselt die Position mit Sureya, so dass er nun bei Jori stand, und sie bei Nazira.\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">&#8222;Nehmen Sie beide bitte die Grundhaltung ein&#8220;, dirigierte die kleine \u00c4gypterin, und Jori und Nazira stellten sich auf. Sureya und Ratan begutachteten die beiden, wie sie da standen, Ratan bohrte Jori kurz den Finger ins Kreuz, damit dieser gerader stand, Sureya legte die H\u00e4nde auf Naziras Schultern und zog diese zur\u00fcck. Dann stellte sich Sureya direkt dicht hinter Nazira, und Ratan ebenso dicht hinter Jori. Beide &#8222;Lehrer&#8220; legten ihren &#8222;Sch\u00fclern&#8220; jeweils eine Hand auf die rechte H\u00fcfte, die andere Hand zwischen die Schulterbl\u00e4tter. Die Musik startete &#8211; ein St\u00fcck mit den gleichen Rhytmus und Geschwindigkeit, wie das zuvor.\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">&#8222;Wir werden Ihnen beiden durch leichten Druck anzeigen, wohin es geht.&#8220; raunte Sureya den beiden zu. &#8222;Und nun &#8211; tanzen Sie!&#8220;\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">Der Eska blickte der kleinen Trill in die Augen. Die Situation f\u00fchlte sich mehr als nur surreal an. Da standen sie beide mitten in diesem Lokal mit dem mehr als passenden Namen\u00a0&#8222;Wunderbar&#8220;, eingerahmt von zwei Senioroffizieren und einem nicht unerheblich kleinen Publikum, das\u00a0gespannt auf das\u00a0Kommende zu sein schien. &#8222;Tanzen wir&#8230;&#8220; grinste Jori etwas schief, als er anfing sich wieder zum Takt der Musik zu bewegen. Dabei versuchte er,\u00a0die Anweisungen von Sureya so gut es ging umzusetzen. Er versuchte dabei,\u00a0mit seinen Gedanken nur im Hier und Jetzt zu sein, sich auf Nazira zu konzentrieren, wobei der die korrigierenden Impulse und Bewegungen von Ratan sp\u00fcrte und sich versuchte,\u00a0diese einzupr\u00e4gen und umzusetzen.<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">Nazira verfolgte einen \u00e4hnlichen Ansatz, wobei sie sich ebenfalls ganz auf Jori konzentrierte &#8211; was ihr nicht schwer fiel &#8211; und ebenso, sich auf den Rhythmus der Musik einzulassen, das Lied zu sp\u00fcren, was ihr als Musikerin eigentlich noch leichter fiel. Die schlanken, starken H\u00e4nde von Sureya auf R\u00fccken und H\u00fcfte verliehen ihr eine gewisse Sicherheit.\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">F\u00fcr ungef\u00e4hr das halbe Lied lang, tanzten sie so in einer vierer-Reihe vor sich hin, was gewiss ein&#8230;interessantes Bild ergab. Daf\u00fcr trat niemand dem anderen mehr auf die F\u00fc\u00dfe, eine eindeutige Verbesserung.\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">Dann wurde der Druck der leitenden H\u00e4nde immer schw\u00e4cher, das konnten sie beide f\u00fchlen. Sureya und Ratan hatten offenbar beschlossen, sie alleine weitertanzen zu lassen&#8230; und jetzt, wo sie einmal im Fluss waren, funktionierte es tats\u00e4chlich! Ein strahlendes L\u00e4cheln breitete sich auf Naziras Gesicht aus, als sie sich weiter auf Joris Augen konzentrierte.\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">Jori f\u00fchlte sich nun\u00a0ebenfalls\u00a0viel wohler ein seiner Haut. Auch er konzentrierte sich auf Naziras Augen und ihr L\u00e4cheln, dass sich als ansteckend erwies. Der Eska ginste nun ebenso breit wie seine Tanzpartnerin, als\u00a0sie\u00a0sich nun tats\u00e4chlich\u00a0unfallfrei\u00a0\u00fcber die Tanzfl\u00e4che bewegten.\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">&#8222;So f\u00e4ngt das richtig an,\u00a0Spa\u00df zu machen&#8230;&#8220; kommentierte Jori mit h\u00f6rbarer Freude in der Stimme die Tatsache, dass er es schaffte Naziras F\u00fc\u00dfe heil zu lassen.<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">Nazira musste kichern. &#8222;Da will ich dir gar nicht widersprechen&#8230;lustig war es vorher doch aber auch irgendwie&#8230;&#8220; dabei wurde ihr L\u00e4cheln einen Hauch schelmischer.<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">&#8222;Hmmm&#8230;.&#8220; machte Jori mit einer leichten Verlegenheit im Gesicht.<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">Als das Lied nach ein paar mehr Takten schlie\u00dflich endete, applaudierten viele der Zuschauer dem Tanzpaar, dass sich so wacker mit Hilfe von Sureya und Ratan geschlagen hatte. Jori hatte aber nur Augen f\u00fcr Nazira, die er breit anl\u00e4chelte. Dann zog er sie pl\u00f6tzlich ganz nah an sich heran und k\u00fcsste sie leidenschaftlich. Was genau ihn dazu hingerissen hatte, wusste er selbst nicht. Die Freude, dass sie diesen Tanz hinbekommen hatten? Das sie eine Lektion in Sachen Tanzen von zwei Senioroffizieren erteilt bekommen hatten? Das sie diese Sache auf der Tanzfl\u00e4che \u00fcberlebt hatten? Oder einfach die Tatsache, dass er mit\u00a0Nazira\u00a0hier\u00a0sein durfte, das beste, was ihm seit langen passieren konnte?<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">Nazira war mehr als \u00fcberrascht, dass sie der sonst so reservierte Jori pl\u00f6tzlicher vor aller Augen k\u00fcsste, und zwar nicht nur leicht, sondern so richtig, und eine verlegene R\u00f6te \u00fcberzog ihre fast wei\u00dfe Haut&#8230; doch das hielt sie nicht davon ab, ihn genauso zur\u00fcckzuk\u00fcssen.\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">Erst, als aus dem Publikum gutm\u00fctge Pfiffe und die obligatorischen Rufe &#8222;Get a room!&#8220; kamen, l\u00f6sten sie sich wieder voneinander und grinsten verlegen.\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">Sureya hob eine Augenbraue, sagte aber nichts dazu. Statt dessen schnappte sie sich Ratan und ging zur\u00fcck zu den anderen. Ja, sie war auch mal so jung gewesen&#8230;aber jede Zeit hatte das ihre, dachte sie sich, als sie den gro\u00dfen Inder an ihrer Seite ansah.\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">Jori und Nazira entfernten sich nun auch wieder von der Tanzfl\u00e4che, um zu ihren Kollegen&#8230;.Freunden&#8230;zur\u00fcckzukehren. Auch, wenn zumindest Nazira f\u00fcr einen Moment Schwierigkeiten hatte, dem Captain in die Augen zu sehen&#8230;\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">&lt;\/RPG&gt;<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">&lt;SUM&gt;<\/p>\n<p class=\"MsoNormal\"># Zeit: SpD -1.2030<\/p>\n<p class=\"MsoNormal\"># Ort: Quartier Jori Tainia<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">Eine v\u00f6llig fertige Nazira f\u00e4llt bei Jori ein, gibt ihm Tips f\u00fcr die Tribbleversorgung, heult sich so richtig \u00fcber ihre Sorgen und N\u00f6te, Emily und Karx betreffend, bei ihm aus und schl\u00e4ft v\u00f6llig ersch\u00f6pft dort ein. Jori tr\u00e4gt sie in sein Bett.\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\"># Zeit: SpD 3.2200<\/p>\n<p class=\"MsoNormal\"># Ort: Station K7 &#8211; Tanbar &#8222;Wunderbar&#8220;\u00a0<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">Jori und Nazira versuchen, zu tanzen. Das geht grandios schief &#8211; bis Sureya und Ratan kurz in die Rolle der Tanzlehrer schl\u00fcpfen&#8230;<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">&lt;\/SUM&gt;<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<p class=\"MsoNormal\">submitted by<\/p>\n<p class=\"MsoNormal\">Lt.j.g. Nazira Tapai<\/p>\n<p class=\"MsoNormal\">CNS, USS Hephaistos<\/p>\n<p class=\"MsoNormal\">&amp;<\/p>\n<p class=\"MsoNormal\">\u00a0<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Hallo Heph, \u00a0 hier ein Copo von Oli und mir. Hat viel Spa\u00df gemacht! \u00a0 Gru\u00df Debora \u00a0 &lt;RPG&gt; # Zeit: SpD\u00a0-1.2030 # Ort:\u00a0Quartier Jori Tainia \u00a0 Der Eska sa\u00df in seinem Quartier nach einem anstrengenden Tag und versuchte trotz seiner M\u00fcdigkeit, irgendwie mit den beiden Tribble von Emily warm zu werden. Derzeit traute er&#8230;<\/p>\n<p class=\"more-link-wrap\"><a href=\"https:\/\/www.sf-germany.org\/einheiten\/uss-hephaistos\/for-every-time-there-is-a-season\/\" class=\"more-link\">Read More<span class=\"screen-reader-text\"> &ldquo;For every time there is a season&rdquo;<\/span> &raquo;<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-8069","post","type-post","status-publish","format-standard","hentry","category-archiv"],"_links":{"self":[{"href":"https:\/\/www.sf-germany.org\/einheiten\/uss-hephaistos\/wp-json\/wp\/v2\/posts\/8069","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sf-germany.org\/einheiten\/uss-hephaistos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sf-germany.org\/einheiten\/uss-hephaistos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sf-germany.org\/einheiten\/uss-hephaistos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sf-germany.org\/einheiten\/uss-hephaistos\/wp-json\/wp\/v2\/comments?post=8069"}],"version-history":[{"count":0,"href":"https:\/\/www.sf-germany.org\/einheiten\/uss-hephaistos\/wp-json\/wp\/v2\/posts\/8069\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sf-germany.org\/einheiten\/uss-hephaistos\/wp-json\/wp\/v2\/media?parent=8069"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sf-germany.org\/einheiten\/uss-hephaistos\/wp-json\/wp\/v2\/categories?post=8069"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sf-germany.org\/einheiten\/uss-hephaistos\/wp-json\/wp\/v2\/tags?post=8069"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}